{"id":150156,"date":"2023-06-20T14:22:21","date_gmt":"2023-06-20T13:22:21","guid":{"rendered":"https:\/\/die-webzeitung.de\/stuttgart\/?p=150156"},"modified":"2023-06-20T14:22:21","modified_gmt":"2023-06-20T13:22:21","slug":"sanierung-und-erweiterung-des-opernhauses","status":"publish","type":"post","link":"https:\/\/die-webzeitung.de\/stuttgart\/2023\/06\/20\/sanierung-und-erweiterung-des-opernhauses\/","title":{"rendered":"Sanierung und Erweiterung des Opernhauses"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Siegerentwurf fu\u0308r Interimsstandort steht fest<\/strong><\/p>\n<p style=\"text-align: justify;\">Stuttgart.| Die Sanierung, Modernisierung und Erweiterung der Wu\u0308rttembergischen Staatstheater Stuttgart ist einen wichtigen Schritt na\u0308her geru\u0308ckt. Im europaweiten Wettbewerb fu\u0308r den erforderlichen Interimsstandort setzte sich der gemeinsame Entwurf von a+r Architekten (Stuttgart) &amp; NL Architects (Amsterdam) durch. Er u\u0308berzeugte eine Jury bestehend aus Fachleuten, Gemeinderats- und Landtagsmitgliedern sowie Vertreterinnen und Vertretern der Stadtverwaltung und des Landes. Das Votum fiel mehrheitlich aus. Im Wettbewerb befanden sich insgesamt 20 Beitra\u0308ge.<\/p>\n<p style=\"text-align: justify;\">Das Interim findet sich in Nachbarschaft zu den Wagenhallen. Es ermo\u0308glicht wa\u0308hrend der acht- bis zehnja\u0308hrigen Sanierung des historischen Littmann-Baus Auffu\u0308hrungen der Staatsoper Stuttgart und des Stuttgarter Balletts und bietet Raum fu\u0308r Produktion, Proben, Lager, Technische Dienste und fu\u0308r Teile der Verwaltung der Wu\u0308rttembergischen Staatstheater (WST). Nach Abschluss der Sanierung und Umzug von Oper und Ballett zuru\u0308ck an den Oberen Schlossgarten werden Teile der Geba\u0308ude fu\u0308r die \u201eMaker City\u201c weitergenutzt. Die \u201eMaker City\u201c (C1-Quartier) za\u0308hlt zu den IBA\u201927-Projekten \u2013 die sta\u0308dtebauliche Entwicklung des Areals rund um die Stuttgarter Wagenhallen wird zum Ort fu\u0308r produktiv-kreative Pilotprojekte und neue Konzepte zur gemischten Stadt.<\/p>\n<p style=\"text-align: justify;\">Erster Bu\u0308rgermeister Dr. Fabian Mayer erkla\u0308rte: \u201eWir haben im Preisgericht zwo\u0308lf Stunden lang getagt \u2013 das hat sich wahrlich gelohnt. Denn das Interim wird von Anfang mehr sein als nur eine Ausweichspielsta\u0308tte fu\u0308r die Staatstheater. Der Entwurf schafft Raum fu\u0308r Wohnen und unterstreicht seine Transformationsfa\u0308higkeit in die Maker City. Es ist ein positiver Auftakt fu\u0308r dieses Quartier, das ein spannendes kulturelles Experimentierfeld wird. Die Spielsta\u0308tte wird die Stadt bereichern und viel neues Publikum anziehen, was der Akzeptanz der Gesamtma\u00dfnahme guttun wird.\u201c Als Baubeginn nannte EBM Mayer das Jahr 2026, mit Beginn der Spielzeit 2029 ko\u0308nnte das Interim in Betrieb genommen werden. Mayer erga\u0308nzte: \u201eDie Begriffe Interim oder Ausweichspielsta\u0308tte reichen nicht an das heran, was hier entstehen wird. Wir wollen mit den Bu\u0308rgerinnen und Bu\u0308rger einen passenden Begriff finden.\u201c<\/p>\n<p style=\"text-align: justify;\">Finanzstaatssekreta\u0308rin Dr. Gisela Splett sagte: \u201eDer gestrige Abschluss des Wettbewerbs fu\u0308r den Interimsstandort ist ein wichtiger Meilenstein fu\u0308r das Gesamtprojekt Sanierung, Modernisierung und Erweiterung der Wu\u0308rttembergischen Staatstheater Stuttgart. Ich gratuliere den Preistra\u0308gern zu ihrem vielversprechenden Siegerentwurf. Denn ich glaube, dass wir eine nachhaltige und wirtschaftliche Lo\u0308sung fu\u0308r dieses komplexe Bauprojekt gefunden haben.\u201c<\/p>\n<p style=\"text-align: justify;\">Kulturstaatssekreta\u0308r Arne Braun sagte: \u201eEndlich ist es soweit: Der Siegerentwurf macht die bisherigen Planungen zur Sanierung des Opernhauses greifbar. Das Signal ist: Jetzt geht\u2018s los! Das wird ein echtes \u201aGro\u00dfes Haus\u2018 fu\u0308r die Zeit, in der es Ballett und Oper beheimatet \u2013 und beste Voraussetzungen fu\u0308r ho\u0308chste ku\u0308nstlerische Qualita\u0308t bietet. Neben einem faszinierenden Stadtentwicklungsprojekt ero\u0308ffnet sich eine wunderbare Chance fu\u0308r Kultur und Publikum, neue Ra\u0308ume zu erobern. Die transparente und offene Architektur fu\u0308gt sich gut in das lebendige Umfeld der Wagenhallen ein. Ballett und Oper ko\u0308nnen sich hier fu\u0308r die Bu\u0308rgerinnen und Bu\u0308rger nochmal aufregend neu und anders entfalten; ein Eldorado fu\u0308r Kreative entsteht. Das Publikum wird\u2019s danken, denn es wird dieses \u201aGro\u00dfe Haus\u2018 fu\u0308r die Zeit im Norden Stuttgarts fu\u0308r sich einnehmen, garantiert.\u201c<\/p>\n<p style=\"text-align: justify;\">Der Vorsitzende des Preisgerichts, Prof. Jens Wittfoht, a\u0308u\u00dferte sich positiv u\u0308ber den Siegerentwurf: \u201eDie Jury hat richtige Arbeit pra\u0308miert. Den Entwurf zeichnet eine Leichtigkeit und La\u0308ssigkeit aus und auch einen schonenden Umgang mit Ressourcen. Das erzeugt Vorfreude auf die Maker City.\u201c<\/p>\n<p style=\"text-align: justify;\">Alexander Lange, Gescha\u0308ftsfu\u0308hrer von a+r ARCHITEKTEN: \u201eUnsere sta\u0308dtebauliche Leitidee ist, schon in der ersten Bauphase an die Folgenutzung zu denken \u2013 im Sinne der O\u0308kologie und Wirtschaftlichkeit, um unno\u0308tigen Abriss zu vermeiden. Eine hohe Flexibilita\u0308t der gebauten Strukturen ermo\u0308glicht verschiedenste gewerbliche Nachnutzungen. Das do\u0308rfliche Wohnen in den obersten Geschossen verknu\u0308pft die Vorteile vom Land mit den Vorteilen der Stadt. Ganz im Sinne von Kurt Tucholsky: \u201a&#8230;vorne Kudamm, hinten Ostsee&#8230;\u2018\u201c.<\/p>\n<p style=\"text-align: justify;\">Marc-Oliver Hendriks, Gescha\u0308ftsfu\u0308hrender Intendant der Wu\u0308rttembergischen Staatstheater Stuttgart, sagte: \u201eIch freue mich sehr u\u0308ber den gelungenen und nachhaltigen Siegerentwurf fu\u0308r den Interimsstandort im Rosensteinquartier. Damit ko\u0308nnen nach vielen Jahren der Planung nun die ersten baulichen Ma\u00dfnahmen im umfangreichen Sanierungsprozess der Wu\u0308rttembergischen Staatstheater Stuttgart begonnen werden.\u201c<\/p>\n<p>Fu\u0308r die weitere Planung des Interimsstandorts beginnen in den kommenden Monaten die Vergabeverfahren: unter anderem fu\u0308r die Planung von Tragwerk, Heizung, Lu\u0308ftung, Sanita\u0308r und Elektro. Verantwortlich dafu\u0308r zeichnet das sta\u0308dtische Hochbauamt mit Unterstu\u0308tzung der Pesch Partner Architektur Stadtplanung GmbH, die als Verfahrensbetreuer verpflichtet wurde.<\/p>\n<p style=\"text-align: justify;\">Daru\u0308ber hinaus erarbeitet die Stadt derzeit den Bebauungsplan und bereitet die Erschlie\u00dfung des Gebiets C1 vor. Grundlage fu\u0308r die Planungen sind die Ergebnisse des offenen internationalen sta\u0308dtebaulichen Wettbewerbs Rosenstein aus dem Jahr 2019. Die Erschlie\u00dfungsarbeiten \u2013 also der Bau von Stra\u00dfen und Kana\u0308len \u2013 sollen Mitte 2025 beginnen.<\/p>\n<p style=\"text-align: justify;\">Die Kosten fu\u0308r die Interimsoper sind mit 224 Millionen veranschlagt. In einem na\u0308chsten Schritt wird der Planungswettbewerb fu\u0308r die Sanierung, Modernisierung und Erweiterung am Oberen Schlossgarten vorbereitet. Fu\u0308r den Baubeginn am Oberen Schlossgarten muss das Interim an den Wagenhallen fertiggestellt werden. Ebenso muss der Werkstattneubau an der Zuckerfabrik fertig sein und die Fla\u0308chen am Oberen Schlossgarten durch die WST freigemacht werden.<\/p>\n<p style=\"text-align: justify;\">Die im Januar von Stadt und Land gegru\u0308ndete ProWST Projektgesellschaft Wu\u0308rttembergische Staatstheater Stuttgart GmbH soll perspektivisch alle Teilprojekte u\u0308bernehmen.<\/p>\n<p style=\"text-align: justify;\">Weitere Informationen zum Ablauf, zu den Teilprojekten und den Beschlu\u0308ssen finden Sie unter <a href=\"https:\/\/www.stuttgart.de\/opernsanierung\" target=\"_blank\" rel=\"noopener\">https:\/\/www.stuttgart.de\/opernsanierung<\/a>.<\/p>\n<p style=\"text-align: justify;\">Die 20 Teilnehmerentwu\u0308rfe des Wettbewerbs sind zu finden unter <a href=\"https:\/\/www.stuttgart.de\/leben\/bauen\/bauprojekte\/wettbewerb-interim-oper.php\" target=\"_blank\" rel=\"noopener\">https:\/\/www.stuttgart.de\/leben\/bauen\/bauprojekte\/wettbewerb-interim-oper.php<\/a>. Daru\u0308ber hinaus sind die Entwu\u0308rfe vom 21. bis 25. Juni 2023, jeweils 13.00 \u2013 19.00 Uhr, im Kunstverein Wagenhalle im Atelier Dundu ausgestellt.<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Siegerentwurf fu\u0308r Interimsstandort steht fest Stuttgart.| Die Sanierung, Modernisierung und Erweiterung der Wu\u0308rttembergischen Staatstheater Stuttgart ist einen wichtigen Schritt na\u0308her geru\u0308ckt. Im europaweiten Wettbewerb fu\u0308r den erforderlichen Interimsstandort setzte sich der gemeinsame Entwurf von a+r Architekten (Stuttgart) &amp; NL Architects (Amsterdam) durch. Er u\u0308berzeugte eine Jury bestehend aus Fachleuten, Gemeinderats- und Landtagsmitgliedern sowie Vertreterinnen und [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":150157,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"footnotes":""},"categories":[2239],"tags":[14857,68,17084,275],"class_list":{"0":"post-150156","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-stuttgart-lokal","8":"tag-die-webzeitung","9":"tag-online-zeitung","10":"tag-opernhaus","11":"tag-stuttgart"},"image_feature":"https:\/\/die-webzeitung.de\/stuttgart\/wp-content\/uploads\/sites\/4\/2023\/06\/Alexander-Lange-spricht-ueber-seinen-Entwurf-in-der-Pressekonferenz-scaled.jpg","author_name":"Redaktion","pure_taxonomies":{"categories":[{"term_id":2239,"name":"Stuttgart","slug":"stuttgart-lokal","term_group":0,"term_taxonomy_id":2252,"taxonomy":"category","description":"Berichte und Informationen aus Stuttgart","parent":1433,"count":949,"filter":"raw","image":""}],"tags":[{"term_id":14857,"name":"Die-Webzeitung","slug":"die-webzeitung","term_group":0,"term_taxonomy_id":14876,"taxonomy":"post_tag","description":"","parent":0,"count":3651,"filter":"raw","image":""},{"term_id":68,"name":"Online-Zeitung","slug":"online-zeitung","term_group":0,"term_taxonomy_id":69,"taxonomy":"post_tag","description":"","parent":0,"count":3621,"filter":"raw","image":""},{"term_id":17084,"name":"Opernhaus","slug":"opernhaus","term_group":0,"term_taxonomy_id":17103,"taxonomy":"post_tag","description":"","parent":0,"count":3,"filter":"raw","image":""},{"term_id":275,"name":"Stuttgart","slug":"stuttgart","term_group":0,"term_taxonomy_id":281,"taxonomy":"post_tag","description":"","parent":0,"count":1205,"filter":"raw","image":""}]},"_links":{"self":[{"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/posts\/150156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/comments?post=150156"}],"version-history":[{"count":1,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/posts\/150156\/revisions"}],"predecessor-version":[{"id":150158,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/posts\/150156\/revisions\/150158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/media\/150157"}],"wp:attachment":[{"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/media?parent=150156"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/categories?post=150156"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/die-webzeitung.de\/stuttgart\/wp-json\/wp\/v2\/tags?post=150156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}